{"id":2579,"date":"2018-05-09T13:25:27","date_gmt":"2018-05-09T12:25:27","guid":{"rendered":"http:\/\/www.tsv-birkenau.de\/?p=2579"},"modified":"2018-05-09T13:25:27","modified_gmt":"2018-05-09T12:25:27","slug":"landesturnfestes-2018","status":"publish","type":"post","link":"https:\/\/www.tsv-birkenau.de\/index.php\/archives\/2579","title":{"rendered":"Landesturnfestes 2018"},"content":{"rendered":"<p><a href=\"https:\/\/www.tsv-birkenau.de\/wp-content\/upload\/logo-landesturnfest-2018-weinheim.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2580 alignleft\" src=\"https:\/\/www.tsv-birkenau.de\/wp-content\/upload\/logo-landesturnfest-2018-weinheim.png\" alt=\"\" width=\"250\" height=\"250\" srcset=\"https:\/\/www.tsv-birkenau.de\/wp-content\/upload\/logo-landesturnfest-2018-weinheim.png 250w, https:\/\/www.tsv-birkenau.de\/wp-content\/upload\/logo-landesturnfest-2018-weinheim-150x150.png 150w, https:\/\/www.tsv-birkenau.de\/wp-content\/upload\/logo-landesturnfest-2018-weinheim-100x100.png 100w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p>Von Fronleichnam (<span class=\"ox-193ef3b1a0-cmpparseddate\">31.05.2018<\/span>) bis Samstag, <span class=\"ox-193ef3b1a0-cmpparseddate\">02.06.2018,<\/span> werden in beiden Sporthallen in <span class=\"ox-193ef3b1a0-cmpparsedlocation\">Birkenau<\/span> (Langenberghalle sowie Hermann-Sattler-Halle) im Rahmen des\u00a0Landesturnfestes 2018 (Ausrichter: Badischer und Schw\u00e4bischer Turnerbund) insgesamt 6 Veranstaltungen (mit jeweils erwarteten 800 \u2013 1000 Zuschauern) ausgerichtet.<!--more--><!--more--><\/p>\n<p>In diesem Zusammenhang kamen die Ausrichter auf den\u00a0TSV <span class=\"ox-193ef3b1a0-cmpparsedlocation\">Birkenau<\/span> zu, ob der Verein diese Veranstaltungen logistisch (Essens-\/Getr\u00e4nkeverkauf \/ Ordnungsdienst etc.) bei den Veranstaltungen in der LBS Halle unterst\u00fctzen kann. Zus\u00e4tzlich werden die Akteure (ca. 300) der Veranstaltungen am Donnerstag und am Freitag mit warmen Essen in der Mensa der Langenbergschule bewirtet.<\/p>\n<p>F\u00fcr die Vorbereitungsarbeiten zu den Veranstaltungen und f\u00fcr die Bewirtung der Akteure (Br\u00f6tchen belegen \/ Essen kochen und ausgeben) ben\u00f6tigen wir dringend noch Unterst\u00fctzung.<\/p>\n<p>F\u00fcr den TSV, aber auch ganz Birkenau, wird ein Gelingen der Veranstaltung sicherlich eine positive Au\u00dfenresonanz haben.<\/p>\n<p>Mit Blick auf die o.g. Zahlen an Veranstaltungen \u00fcber 3 Tage, die Anzahl der erwarteten Zuschauer und Akteure kann sich jeder vorstellen, dass hier eine Vielzahl von Helfern gefragt sein wird.<\/p>\n<p>Bitte unterst\u00fctzt den Verein!<\/p>\n<p>Die Doodle\u00a0Helferlisten sind:<\/p>\n<p><a href=\"https:\/\/doodle.com\/poll\/bedbycr3hmqdinkm\" target=\"_blank\" rel=\"noopener\">Doodle: Landesturnfest Donnerstag 31.5.2018<\/a><\/p>\n<p><a href=\"https:\/\/doodle.com\/poll\/33k5k87x24gp3dyw\" target=\"_blank\" rel=\"noopener\">Doodle: Landesturnfest Freitag 1.6.2018<\/a><\/p>\n<p><a href=\"https:\/\/doodle.com\/poll\/87b7fbdwdkvwcfvu\" target=\"_blank\" rel=\"noopener\">Doodle: Landesturnfest Samstag 2.6.2018<\/a><\/p>\n<p>Es sind aktuell noch viele Dienste offen.<\/p>\n<p class=\"ox-193ef3b1a0-MsoNormal\">Bitte beachtet in der obersten Zeile, wie viele Personen f\u00fcr die versch. Dienste ben\u00f6tigt werden. Sollte keine Anzahl dabei stehen, so sind es 4 Personen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Fronleichnam (31.05.2018) bis Samstag, 02.06.2018, werden in beiden Sporthallen in Birkenau (Langenberghalle sowie Hermann-Sattler-Halle) im Rahmen des\u00a0Landesturnfestes 2018 (Ausrichter: Badischer und Schw\u00e4bischer Turnerbund) insgesamt 6 Veranstaltungen (mit jeweils erwarteten [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2579","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Frank Buckenauer","author_link":"https:\/\/www.tsv-birkenau.de\/index.php\/archives\/author\/frankbuckenauer"},"uagb_comment_info":7,"uagb_excerpt":"Von Fronleichnam (31.05.2018) bis Samstag, 02.06.2018, werden in beiden Sporthallen in Birkenau (Langenberghalle sowie Hermann-Sattler-Halle) im Rahmen des\u00a0Landesturnfestes 2018 (Ausrichter: Badischer und Schw\u00e4bischer Turnerbund) insgesamt 6 Veranstaltungen (mit jeweils erwarteten [&hellip;]","_links":{"self":[{"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/2579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=2579"}],"version-history":[{"count":1,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/2579\/revisions"}],"predecessor-version":[{"id":2581,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/2579\/revisions\/2581"}],"wp:attachment":[{"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=2579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=2579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=2579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}